{"id":2787,"date":"2025-09-26T21:49:47","date_gmt":"2025-09-26T21:49:47","guid":{"rendered":"https:\/\/smokebroker.ch\/?post_type=product&#038;p=2787"},"modified":"2026-08-27T05:04:01","modified_gmt":"2026-08-27T05:04:01","slug":"purize-xtra-slim-size-50-stueck-pink","status":"publish","type":"product","link":"https:\/\/smokebroker.ch\/it\/shop\/purize-xtra-slim-size-50-stueck-pink\/","title":{"rendered":"Purize &#8211; Xtra Slim Size &#8211; 50 St\u00fcck &#8211; Pink"},"content":{"rendered":"<h5>Purize &#8211; Xtra Slim Size &#8211; 50 St\u00fcck &#8211; Pink<\/h5>\n<p>Unser XTRA Slim Size Filter wird geliefert im wiederverschliessbaren und praktischen 50er Vorratsbeutel. Unser Vorratsbeutel sorgt nicht nur daf\u00fcr, dass Deine Filter nice pr\u00e4sentiert werden, sondern schafft auch gute Lagerungsbedingungen f\u00fcr Deine Filter und sch\u00fctzt sie vor \u00e4usseren Einfl\u00fcssen. So hast Du lange etwas von Deinen Aktivkohlefiltern und kannst sie sorgenfrei transportieren!<\/p>\n<p>Aktivkohle auf Kokosnuss-Basis reduziert die Schadstoffaufnahme und verschafft Dir ein k\u00fchles und trockenes Raucherlebnis. Geeignet sind unsere Aktivkohlefilter f\u00fcr ALLE Arten von Selbstgedrehten! Auch in Sachen Handling haben wir etwas Besonders f\u00fcr Dich: Da beide Endkappen aus Keramik bestehen, gibt es keine Einsteck- oder Eindrehrichtung zu beachten und Du sparst Dir unter Umst\u00e4nden nervige \u201eBau-Arbeit\u201c.<\/p>\n<p>PURIZE\u00ae Filters sind aus umweltbewussten Rohstoffen gefertigt und \u201eMade in Germany\u201c.<\/p>\n<h5>Vorteile:<\/h5>\n<ul>\n<li>F\u00fcr alle Selbstgedrehten geeignet<\/li>\n<li>Milderes Raucherlebnis<\/li>\n<li>Hochwertige Aktivkohle<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Purize &#8211; Xtra Slim Size &#8211; 50 St\u00fcck &#8211; Pink Unser XTRA Slim Size Filter wird geliefert im wiederverschliessbaren und praktischen 50er Vorratsbeutel. Unser Vorratsbeutel sorgt nicht nur daf\u00fcr, dass Deine Filter nice pr\u00e4sentiert werden, sondern schafft auch gute Lagerungsbedingungen f\u00fcr Deine Filter und sch\u00fctzt sie vor \u00e4usseren Einfl\u00fcssen. So hast Du lange etwas von [&hellip;]<\/p>\n","protected":false},"featured_media":3971,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"taste":[],"origin":[],"packaging-type":[557],"size":[548],"strength":[],"weight":[],"product_brand":[379],"product_cat":[35,60],"product_tag":[],"class_list":{"0":"post-2787","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"packaging-type-pack","7":"size-50-stueck","8":"product_brand-purize","9":"product_cat-aktivkohlefilter","10":"product_cat-purize","12":"first","13":"instock","14":"taxable","15":"shipping-taxable","16":"purchasable","17":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/smokebroker.ch\/it\/wp-json\/wp\/v2\/product\/2787","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/smokebroker.ch\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/smokebroker.ch\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/smokebroker.ch\/it\/wp-json\/wp\/v2\/comments?post=2787"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smokebroker.ch\/it\/wp-json\/wp\/v2\/media\/3971"}],"wp:attachment":[{"href":"https:\/\/smokebroker.ch\/it\/wp-json\/wp\/v2\/media?parent=2787"}],"wp:term":[{"taxonomy":"taste","embeddable":true,"href":"https:\/\/smokebroker.ch\/it\/wp-json\/wp\/v2\/taste?post=2787"},{"taxonomy":"origin","embeddable":true,"href":"https:\/\/smokebroker.ch\/it\/wp-json\/wp\/v2\/origin?post=2787"},{"taxonomy":"packaging-type","embeddable":true,"href":"https:\/\/smokebroker.ch\/it\/wp-json\/wp\/v2\/packaging-type?post=2787"},{"taxonomy":"size","embeddable":true,"href":"https:\/\/smokebroker.ch\/it\/wp-json\/wp\/v2\/size?post=2787"},{"taxonomy":"strength","embeddable":true,"href":"https:\/\/smokebroker.ch\/it\/wp-json\/wp\/v2\/strength?post=2787"},{"taxonomy":"weight","embeddable":true,"href":"https:\/\/smokebroker.ch\/it\/wp-json\/wp\/v2\/weight?post=2787"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/smokebroker.ch\/it\/wp-json\/wp\/v2\/product_brand?post=2787"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/smokebroker.ch\/it\/wp-json\/wp\/v2\/product_cat?post=2787"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/smokebroker.ch\/it\/wp-json\/wp\/v2\/product_tag?post=2787"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}