{"id":7668,"date":"2026-09-02T18:37:21","date_gmt":"2026-09-02T18:37:21","guid":{"rendered":"https:\/\/smokebroker.ch\/?post_type=product&#038;p=7668"},"modified":"2026-09-02T18:48:31","modified_gmt":"2026-09-02T18:48:31","slug":"budbouncys-5gr-red-libanese","status":"publish","type":"product","link":"https:\/\/smokebroker.ch\/fr\/shop\/budbouncys-5gr-red-libanese\/","title":{"rendered":"BudBouncy&#8217;s 5gr. Red Libanese"},"content":{"rendered":"<h3>BudBouncy Red Libanese \u2013 5g<\/h3>\n<p><strong>Aromatisch, harzig und charaktervoll \u2013 die BudBouncy Red Libanese \u00fcberzeugt mit ihrem traditionellen Profil und hochwertiger Schweizer Qualit\u00e4t.<\/strong><\/p>\n<p>Die\u00a0<strong>BudBouncy Red Libanese<\/strong>\u00a0ist eine sorgf\u00e4ltig verarbeitete CBD-Sorte mit einem charakteristischen, w\u00fcrzig-erdigen Aroma. Die kompakte Struktur und die harzige Beschaffenheit verleihen dem Produkt seinen besonderen Charakter.<\/p>\n<p>Die Bl\u00fcten stammen aus Schweizer Indoor-Anbau und werden ohne k\u00fcnstliche Aromen oder unn\u00f6tige Zus\u00e4tze verarbeitet. Mit\u00a0<strong>5g Inhalt<\/strong>\u00a0ist die Red Libanese ideal f\u00fcr alle, die eine aromatische CBD-Sorte mit einem etwas kr\u00e4ftigeren und traditionellen Profil suchen.<\/p>","protected":false},"excerpt":{"rendered":"<p>BudBouncy Red Libanese \u2013 5g Aromatisch, harzig und charaktervoll \u2013 die BudBouncy Red Libanese \u00fcberzeugt mit ihrem traditionellen Profil und hochwertiger Schweizer Qualit\u00e4t. Die\u00a0BudBouncy Red Libanese\u00a0ist eine sorgf\u00e4ltig verarbeitete CBD-Sorte mit einem charakteristischen, w\u00fcrzig-erdigen Aroma. Die kompakte Struktur und die harzige Beschaffenheit verleihen dem Produkt seinen besonderen Charakter. Die Bl\u00fcten stammen aus Schweizer Indoor-Anbau und [&hellip;]<\/p>\n","protected":false},"featured_media":7670,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"taste":[],"origin":[],"packaging-type":[],"size":[],"strength":[],"weight":[],"product_brand":[367],"product_cat":[30,648],"product_tag":[],"class_list":{"0":"post-7668","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-budbouncys","7":"product_cat-budbouncy","8":"product_cat-hash","10":"first","11":"instock","12":"taxable","13":"shipping-taxable","14":"purchasable","15":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/smokebroker.ch\/fr\/wp-json\/wp\/v2\/product\/7668","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/smokebroker.ch\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/smokebroker.ch\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/smokebroker.ch\/fr\/wp-json\/wp\/v2\/comments?post=7668"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smokebroker.ch\/fr\/wp-json\/wp\/v2\/media\/7670"}],"wp:attachment":[{"href":"https:\/\/smokebroker.ch\/fr\/wp-json\/wp\/v2\/media?parent=7668"}],"wp:term":[{"taxonomy":"taste","embeddable":true,"href":"https:\/\/smokebroker.ch\/fr\/wp-json\/wp\/v2\/taste?post=7668"},{"taxonomy":"origin","embeddable":true,"href":"https:\/\/smokebroker.ch\/fr\/wp-json\/wp\/v2\/origin?post=7668"},{"taxonomy":"packaging-type","embeddable":true,"href":"https:\/\/smokebroker.ch\/fr\/wp-json\/wp\/v2\/packaging-type?post=7668"},{"taxonomy":"size","embeddable":true,"href":"https:\/\/smokebroker.ch\/fr\/wp-json\/wp\/v2\/size?post=7668"},{"taxonomy":"strength","embeddable":true,"href":"https:\/\/smokebroker.ch\/fr\/wp-json\/wp\/v2\/strength?post=7668"},{"taxonomy":"weight","embeddable":true,"href":"https:\/\/smokebroker.ch\/fr\/wp-json\/wp\/v2\/weight?post=7668"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/smokebroker.ch\/fr\/wp-json\/wp\/v2\/product_brand?post=7668"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/smokebroker.ch\/fr\/wp-json\/wp\/v2\/product_cat?post=7668"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/smokebroker.ch\/fr\/wp-json\/wp\/v2\/product_tag?post=7668"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}